{"id":1300,"date":"2025-08-22T17:15:58","date_gmt":"2025-08-22T15:15:58","guid":{"rendered":"https:\/\/edt.blogdns.net\/wordpress\/?p=1300"},"modified":"2025-08-23T09:31:59","modified_gmt":"2025-08-23T07:31:59","slug":"aol-annonce-la-fin-de-son-service-dacces-internet-par-lignes-telephoniques-dial-up-connection","status":"publish","type":"post","link":"https:\/\/edt.blogdns.net\/wordpress\/2025\/08\/22\/aol-annonce-la-fin-de-son-service-dacces-internet-par-lignes-telephoniques-dial-up-connection\/","title":{"rendered":"AOL annonce la fin de son service d&rsquo;acc\u00e8s internet par lignes t\u00e9l\u00e9phoniques (dial-up connection)"},"content":{"rendered":"\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-ad2f72ca wp-block-group-is-layout-flex\">\n<p class=\"has-drop-cap\"><strong>AOL <\/strong>l&rsquo;un des <strong>pionniers de l&rsquo;internet grand public<\/strong> \u00e9teindra son service d&rsquo;acc\u00e8s internet par ligne l\u00e9l\u00e9phonique fin septembre. La connexion par ligne t\u00e9l\u00e9phone commut\u00e9e (la paire cuivre utilis\u00e9e avant la fibre optique) n\u00e9cessitait dans les ann\u00e9es 1990 d&rsquo;utiliser un modem charg\u00e9 de convertir les informations num\u00e9riques en signaux analogiques (et inversement).<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2328\" height=\"1648\" src=\"https:\/\/i0.wp.com\/edt.blogdns.net\/wordpress\/wp-content\/uploads\/2025\/08\/Modem-usr-courier-v34-front-online.jpg?fit=2328%2C1648&amp;ssl=1\" alt=\"\" class=\"wp-image-1308\" style=\"object-fit:cover\" srcset=\"https:\/\/i0.wp.com\/edt.blogdns.net\/wordpress\/wp-content\/uploads\/2025\/08\/Modem-usr-courier-v34-front-online.jpg?w=2328&amp;ssl=1 2328w, https:\/\/i0.wp.com\/edt.blogdns.net\/wordpress\/wp-content\/uploads\/2025\/08\/Modem-usr-courier-v34-front-online.jpg?resize=300%2C212&amp;ssl=1 300w, https:\/\/i0.wp.com\/edt.blogdns.net\/wordpress\/wp-content\/uploads\/2025\/08\/Modem-usr-courier-v34-front-online.jpg?resize=1024%2C725&amp;ssl=1 1024w, https:\/\/i0.wp.com\/edt.blogdns.net\/wordpress\/wp-content\/uploads\/2025\/08\/Modem-usr-courier-v34-front-online.jpg?resize=768%2C544&amp;ssl=1 768w, https:\/\/i0.wp.com\/edt.blogdns.net\/wordpress\/wp-content\/uploads\/2025\/08\/Modem-usr-courier-v34-front-online.jpg?resize=1536%2C1087&amp;ssl=1 1536w, https:\/\/i0.wp.com\/edt.blogdns.net\/wordpress\/wp-content\/uploads\/2025\/08\/Modem-usr-courier-v34-front-online.jpg?resize=2048%2C1450&amp;ssl=1 2048w, https:\/\/i0.wp.com\/edt.blogdns.net\/wordpress\/wp-content\/uploads\/2025\/08\/Modem-usr-courier-v34-front-online.jpg?resize=1200%2C849&amp;ssl=1 1200w, https:\/\/i0.wp.com\/edt.blogdns.net\/wordpress\/wp-content\/uploads\/2025\/08\/Modem-usr-courier-v34-front-online.jpg?w=1680&amp;ssl=1 1680w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><figcaption class=\"wp-element-caption\">Modem US Robotics de type Courier<\/figcaption><\/figure>\n<\/div>\n\n\n\n<p>Lors de la connexion le modem \u00e9mettait un bruit reconnaissable entre mille, fait de gr\u00e9sillements et de \u00ab\u00a0bips\u00a0\u00bb aigus, qui a accompagn\u00e9 des millions de personnes \u00e0 travers le monde.<\/p>\n\n\n\n<p class=\"has-drop-cap\">L&rsquo;entreprise am\u00e9ricaine a annonc\u00e9 dans <a href=\"https:\/\/help.aol.com\/articles\/dial-up-internet-to-be-discontinued\">une note de blog<\/a> avoir \u00e9valu\u00e9 l&rsquo;int\u00e9r\u00eat de maintenir ce service: <em>&nbsp;\u00ab\u00a0AOL \u00e9value r\u00e9guli\u00e8rement ses produits et services et a d\u00e9cid\u00e9 de mettre fin \u00e0 l&rsquo;acc\u00e8s internet par ligne commut\u00e9e&nbsp;<\/em>[\u00e0 l&rsquo;aide d&rsquo;une prise t\u00e9l\u00e9phonique traditionnelle]<em>. Ce service et les logiciels associ\u00e9s, le logiciel AOL Dialer et le navigateur AOL Shield, optimis\u00e9s pour les anciens syst\u00e8mes d&rsquo;exploitation et les connexions internet par ligne commut\u00e9e, seront supprim\u00e9s\u00a0\u00bb<\/em>.<\/p>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-7fcf821d wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img data-recalc-dims=\"1\" decoding=\"async\" srcset=\"https:\/\/edt.blogdns.net\/wordpress\/wp-content\/uploads\/2025\/08\/Screenshot-from-2025-08-22-16-16-16.png ,https:\/\/edt.blogdns.net\/wordpress\/wp-content\/uploads\/2025\/08\/Screenshot-from-2025-08-22-16-16-16.png 780w, https:\/\/edt.blogdns.net\/wordpress\/wp-content\/uploads\/2025\/08\/Screenshot-from-2025-08-22-16-16-16.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/i0.wp.com\/edt.blogdns.net\/wordpress\/wp-content\/uploads\/2025\/08\/Screenshot-from-2025-08-22-16-16-16.png?resize=648%2C520&#038;ssl=1\" alt=\"\" class=\"uag-image-1303\" width=\"648\" height=\"520\" title=\"Screenshot from 2025-08-22 16-16-16\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<p class=\"has-drop-cap\">AOL avait d\u00e9j\u00e0 mis fin en 2017 au service <strong>AOL Instant Messenger<\/strong>, un service de messagerie instantan\u00e9 pionnier \u00e0 la fin des ann\u00e9es 1990.<\/p>\n\n\n\n<p class=\"has-drop-cap\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-medium is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"888\" height=\"538\" src=\"https:\/\/i0.wp.com\/edt.blogdns.net\/wordpress\/wp-content\/uploads\/2025\/08\/Screenshot-from-2025-08-22-15-45-58.png?fit=300%2C182&amp;ssl=1\" alt=\"\" class=\"wp-image-1301\" srcset=\"https:\/\/i0.wp.com\/edt.blogdns.net\/wordpress\/wp-content\/uploads\/2025\/08\/Screenshot-from-2025-08-22-15-45-58.png?w=888&amp;ssl=1 888w, https:\/\/i0.wp.com\/edt.blogdns.net\/wordpress\/wp-content\/uploads\/2025\/08\/Screenshot-from-2025-08-22-15-45-58.png?resize=300%2C182&amp;ssl=1 300w, https:\/\/i0.wp.com\/edt.blogdns.net\/wordpress\/wp-content\/uploads\/2025\/08\/Screenshot-from-2025-08-22-15-45-58.png?resize=768%2C465&amp;ssl=1 768w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure>\n\n\n\n<p class=\"has-drop-cap\">AOL Instant messenger avait \u00e9t\u00e9 lanc\u00e9 en 1997. En 20217 WhatsApp ou Messenger avaient, de fait, remplac\u00e9 AOL Instant Messenger en gagnant une audience largement sup\u00e9rieure.<\/p>\n\n\n\n<p>La soci\u00e9t\u00e9 AOL avait \u00e9t\u00e9 rachet\u00e9e en 2001 par le groupe Time Warner pour 165 milliards de dollars. Elle \u00e9tait devenue l&rsquo;un des symboles de la bulle internet, qui avait vu la valeur de plusieurs g\u00e9ants du secteur s&rsquo;effondrer au d\u00e9but des ann\u00e9es 2000. En 2015, l&rsquo;op\u00e9rateur am\u00e9ricain Verizon avait d\u00e9pens\u00e9 4,4 milliards de dollars pour racheter l&rsquo;entreprise.&nbsp;AOL est aujourd&rsquo;hui fusionn\u00e9 avec Yahoo! sous le nom Oath, autre g\u00e9ant d\u00e9chu d&rsquo;internet, apr\u00e8s son rachat par le fonds d&rsquo;investissement Apollo Global Management.<\/p>\n\n\n\n<p class=\"has-drop-cap\">Selon les donn\u00e9es du recensement am\u00e9ricain de 2022, environ 175 000 m\u00e9nages am\u00e9ricains se connectent encore \u00e0 Internet via des services commut\u00e9s. Ces utilisateurs vivent g\u00e9n\u00e9ralement dans des zones rurales o\u00f9 l\u2019infrastructure haut d\u00e9bit n\u2019existe pas ou reste prohibitive \u00e0 installer.<\/p>\n\n\n\n<p>Pour ces utilisateurs, les alternatives sont limit\u00e9es. L\u2019Internet par satellite dessert maintenant environ 2 \u00e0 3 millions d\u2019abonn\u00e9s am\u00e9ricains r\u00e9partis entre divers services, offrant des vitesses bien sup\u00e9rieures \u00e0 celles de l\u2019acc\u00e8s commut\u00e9, mais souvent avec des plafonds de donn\u00e9es et une latence plus \u00e9lev\u00e9e. Le haut d\u00e9bit traditionnel via des connexions DSL, par c\u00e2ble ou par fibre optique dessert la grande majorit\u00e9 des utilisateurs d\u2019Internet aux \u00c9tats-Unis, mais n\u00e9cessite des investissements dans les infrastructures qui n\u2019ont pas toujours de sens \u00e9conomique dans les zones peu peupl\u00e9es.<\/p>\n\n\n\n<p>La persistance de l\u2019acc\u00e8s commut\u00e9 met en \u00e9vidence la fracture num\u00e9rique persistante aux \u00c9tats-Unis. Alors que les utilisateurs urbains b\u00e9n\u00e9ficient de connexions par fibre gigabit, certains r\u00e9sidents ruraux s\u2019appuient toujours sur la m\u00eame technologie qui a aliment\u00e9 l\u2019Internet en 1995. M\u00eame des t\u00e2ches de base comme le chargement d\u2019une page Web moderne, con\u00e7ue en supposant des vitesses de haut d\u00e9bit, peuvent prendre quelques minutes sur une connexion commut\u00e9e, ou parfois ne pas fonctionner du tout.<\/p>\n\n\n\n<p>L\u2019\u00e9cart entre les connexions Internet commut\u00e9es et les connexions Internet modernes est stup\u00e9fiant. Une connexion commut\u00e9e typique fournit 0,056 m\u00e9gabits par seconde, tandis qu\u2019une connexion fibre optique moyenne fournit 500 Mbps, soit pr\u00e8s de 9 000 fois plus rapide. Pour mettre cela en perspective, le t\u00e9l\u00e9chargement d\u2019une seule photo haute r\u00e9solution qui se charge instantan\u00e9ment sur le haut d\u00e9bit prendrait plusieurs minutes en ligne commut\u00e9e. Un film diffus\u00e9 en temps r\u00e9el sur Netflix n\u00e9cessiterait des jours de t\u00e9l\u00e9chargement. Mais pour des millions d\u2019Am\u00e9ricains qui ont v\u00e9cu \u00e0 l\u2019\u00e8re de l\u2019acc\u00e8s commut\u00e9, ces statistiques ne racontent qu\u2019une partie de l\u2019histoire.<\/p>\n\n\n\n<p class=\"has-drop-cap\"><strong>En France<\/strong>,&nbsp;Orange a d\u00e9connect\u00e9 162 villes du r\u00e9seau ADSL, soit environ 20&nbsp;000 clients, \u00e0 la fin du mois de janvier 2025. Le r\u00e9seau cuivre doit \u00eatre progressivement d\u00e9branch\u00e9 d&rsquo;ici fin 2030, pour \u00eatre remplac\u00e9 par la fibre optique sur la totalit\u00e9 du territoire<\/p>\n\n\n\n<div class=\"wp-block-uagb-separator uagb-block-545e731c\"><div class=\"wp-block-uagb-separator__inner\" style=\"--my-background-image:\"><\/div><\/div>\n\n\n\n<p>Voil\u00e0.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<p><em>Source:<\/em> <a href=\"https:\/\/arstechnica.com\/gadgets\/2025\/08\/aol-will-finally-end-1991-dial-up-internet-service-thats-older-than-smartphones\/\">arstechnica<\/a><\/p>\n\n\n\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>AOL l&rsquo;un des pionniers de l&rsquo;internet grand public \u00e9teindra son service d&rsquo;acc\u00e8s internet par ligne l\u00e9l\u00e9phonique fin septembre. La connexion par ligne t\u00e9l\u00e9phone commut\u00e9e (la paire cuivre utilis\u00e9e avant la fibre optique) n\u00e9cessitait dans les ann\u00e9es 1990 d&rsquo;utiliser un modem charg\u00e9 de convertir les informations num\u00e9riques en signaux analogiques (et inversement). Lors de la connexion &hellip; <a href=\"https:\/\/edt.blogdns.net\/wordpress\/2025\/08\/22\/aol-annonce-la-fin-de-son-service-dacces-internet-par-lignes-telephoniques-dial-up-connection\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;AOL annonce la fin de son service d&rsquo;acc\u00e8s internet par lignes t\u00e9l\u00e9phoniques (dial-up connection)&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[13,8],"tags":[53,30],"class_list":["post-1300","post","type-post","status-publish","format-standard","hentry","category-internet","category-vie-privee","tag-aol","tag-internet"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"post-thumbnail":false},"uagb_author_info":{"display_name":"marc","author_link":"https:\/\/edt.blogdns.net\/wordpress\/author\/marc_taviaux\/"},"uagb_comment_info":0,"uagb_excerpt":"AOL l&rsquo;un des pionniers de l&rsquo;internet grand public \u00e9teindra son service d&rsquo;acc\u00e8s internet par ligne l\u00e9l\u00e9phonique fin septembre. La connexion par ligne t\u00e9l\u00e9phone commut\u00e9e (la paire cuivre utilis\u00e9e avant la fibre optique) n\u00e9cessitait dans les ann\u00e9es 1990 d&rsquo;utiliser un modem charg\u00e9 de convertir les informations num\u00e9riques en signaux analogiques (et inversement). Lors de la connexion\u2026","_links":{"self":[{"href":"https:\/\/edt.blogdns.net\/wordpress\/wp-json\/wp\/v2\/posts\/1300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edt.blogdns.net\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/edt.blogdns.net\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/edt.blogdns.net\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/edt.blogdns.net\/wordpress\/wp-json\/wp\/v2\/comments?post=1300"}],"version-history":[{"count":13,"href":"https:\/\/edt.blogdns.net\/wordpress\/wp-json\/wp\/v2\/posts\/1300\/revisions"}],"predecessor-version":[{"id":1318,"href":"https:\/\/edt.blogdns.net\/wordpress\/wp-json\/wp\/v2\/posts\/1300\/revisions\/1318"}],"wp:attachment":[{"href":"https:\/\/edt.blogdns.net\/wordpress\/wp-json\/wp\/v2\/media?parent=1300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/edt.blogdns.net\/wordpress\/wp-json\/wp\/v2\/categories?post=1300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/edt.blogdns.net\/wordpress\/wp-json\/wp\/v2\/tags?post=1300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}