{"id":795,"date":"2022-07-21T17:21:42","date_gmt":"2022-07-21T15:21:42","guid":{"rendered":"https:\/\/edt.blogdns.net\/wordpress\/?p=795"},"modified":"2022-09-30T19:24:03","modified_gmt":"2022-09-30T17:24:03","slug":"la-fibre-nouvelle-installation-et-experience-de-lipv6","status":"publish","type":"post","link":"https:\/\/edt.blogdns.net\/wordpress\/2022\/07\/21\/la-fibre-nouvelle-installation-et-experience-de-lipv6\/","title":{"rendered":"La Fibre &#8211; Nouvelle installation et exp\u00e9rience de l&rsquo;IPv6"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Si vous pouvez lire ces quelques lignes c&rsquo;est que mes services auto-h\u00e9berg\u00e9s sont de nouveau en ligne (comprendre: accessibles dans le cyberespace). Il y a 20 jours mon \u00e9pouse et moi d\u00e9m\u00e9nagions  dans une maison situ\u00e9e \u00e0 100 m du point de livraison de notre fournisseur d&rsquo;acc\u00e8s internet (la maison est \u00e0 70 m de la rue). Les serveurs h\u00e9berg\u00e9s \u00e0 la maison ont \u00e9t\u00e9 d\u00e9m\u00e9nag\u00e9s \u00e9galement et leur raccordement \u00e0 la fibre optique a \u00e9t\u00e9 n\u00e9cessaire.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Le raccordement<\/h2>\n\n\n\n<p>Pour \u00eatre raccord\u00e9 au point de livraison de la fibre optique (la boite sur poteau, dans la rue) il faut mettre un conduit \u00e0 disposition du technicien charg\u00e9 de l&rsquo;op\u00e9ration. En g\u00e9n\u00e9ral, le conduit du t\u00e9l\u00e9phone est utilis\u00e9 \u00e0 cet effet. Dans notre cas, le conduit enterr\u00e9 du t\u00e9l\u00e9phone \u00e9tant obstru\u00e9, il fallait soit ouvrir une tranch\u00e9e, soit utiliser un autre conduit existant. Le plus simple \u00e9tant d&rsquo;opter pour un conduit existant, j&rsquo;avais le choix entre:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li> le conduit \u00e9lectrique alimentant la maison depuis le compteur en limite de propri\u00e9t\u00e9;<\/li><li> le conduit d&rsquo;\u00e9vacuation des eaux us\u00e9es raccordant la maison au r\u00e9seau du tout \u00e0 l&rsquo;\u00e9gout.    <\/li><\/ul>\n\n\n\n<p>J&rsquo;ai opt\u00e9 pour le passage dans le conduit \u00e9lectrique (il n&rsquo;y circule aucune mati\u00e8re susceptible d&rsquo;occasionner des incidents). La faisabilit\u00e9 de l&rsquo;op\u00e9ration a \u00e9t\u00e9 test\u00e9e par passage d&rsquo;une aiguille en fibre de verre de diam\u00e8tre 4.5 mm depuis la sortie du conduit dans le sous-sol de la maison jusqu&rsquo;\u00e0 la limite de propri\u00e9t\u00e9 (soit sur environ 75 m de longueur). La validation \u00e9tant faite,  pour trouver l&rsquo;entr\u00e9e dans le conduit cot\u00e9 rue il a fallu creuser le terrain sur environ 1 m de profondeur derri\u00e8re l&rsquo;armoire de raccordement EDF. Ensuite d\u00e9gager la zone de raccordement entre conduit principal enterr\u00e9 sur 70 m (tube orange semi flexible diam\u00e8tre 100 mm) et le c\u00e2ble \u00e9lectrique en gaine flexible grise de plus petit diam\u00e8tre.  L&rsquo;extr\u00e9mit\u00e9 d&rsquo;un conduit flexible diam\u00e8tre 50 mm a \u00e9t\u00e9 engag\u00e9e dans le conduit \u00e9lectrique principal. Ce conduit flexible a ensuite \u00e9t\u00e9 enterr\u00e9 jusqu&rsquo;\u00e0 d\u00e9boucher au pied du poteau t\u00e9l\u00e9phone en limite de propri\u00e9t\u00e9. L&rsquo;aiguille en fibre de verre a \u00e9t\u00e9 pouss\u00e9e depuis l&rsquo;extr\u00e9mit\u00e9 du conduit cot\u00e9 rue vers la maison pour enfin d\u00e9boucher derri\u00e8re le tableau de distribution \u00e9lectrique de la maison. L&rsquo;aiguille \u00e9tant en place, le technicien charg\u00e9 du raccordement a attach\u00e9 l&rsquo;extr\u00e9mit\u00e9 de la fibre optique \u00e0 l&rsquo;aiguille et tir\u00e9 celle ci depuis la maison dans les 70 m de conduit enterr\u00e9. <\/p>\n\n\n\n<p class=\"has-drop-cap\">Pour r\u00e9aliser l&rsquo;op\u00e9ration il m&rsquo;a fallu une b\u00eache, une pioche, une barre \u00e0 mine, une aiguille de 100 m de fibre de verre sur touret (100 \u20ac chez votre grande surface de bricolage), quelques m\u00e8tres de conduit de r\u00e9cup\u00e9ration et quelques essais et \u00e9checs. Il faut \u00e9galement un peu de pers\u00e9v\u00e9rance et ne pas h\u00e9siter \u00e0 demander de l&rsquo;aide dans les moments de d\u00e9couragement.  En tout il a fallu environ deux semaines pour la pr\u00e9paration et deux jours pour l&rsquo;installation effective de la fibre optique (incluant la prise de rendez-vous avec le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Fournisseur_d%27acc%C3%A8s_%C3%A0_Internet\" target=\"_blank\" rel=\"noreferrer noopener\">FAI<\/a>).    <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les mis\u00e8res de l&rsquo;IPv4<\/h2>\n\n\n\n<p class=\"has-drop-cap\">Une fois le raccordement \u00e0 l&rsquo;internet assur\u00e9 par fibre optique (abonnement de 25 \u20ac\/mois chez RED by SFR) et pass\u00e9 l&rsquo;enthousiasme suscit\u00e9 par les tests de d\u00e9bit (1 Gbit\/s), les surprises s&rsquo;accumulent apr\u00e8s l&rsquo;installation de mes serveurs.  Premi\u00e8re d\u00e9convenue: apr\u00e8s consultation de l&rsquo;interface d&rsquo;administration de la \u00ab\u00a0box internet\u00a0\u00bb install\u00e9e par RED, les services de <a rel=\"noreferrer noopener\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Network_address_translation\" target=\"_blank\">NAT<\/a> (le traducteur d&rsquo;adresses r\u00e9seau) en <a rel=\"noreferrer noopener\" href=\"https:\/\/fr.wikipedia.org\/wiki\/IPv4\" target=\"_blank\">IPv4<\/a> ne sont pas accessibles. Apr\u00e8s v\u00e9rification aupr\u00e8s des forums techniques traitant des r\u00e9seaux fibre optique, je comprends que les FAI appliquent depuis peu des mesures techniques d\u00e9sign\u00e9es par le terme <a rel=\"noreferrer noopener\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Carrier-grade_NAT\" target=\"_blank\">CGNAT<\/a> (Carrier Grade &#8211; Network Access Translation) pour pallier \u00e0 la p\u00e9nurie d&rsquo;adresses internet disponibles en IPv4. Pour faire simple, cette strat\u00e9gie consiste \u00e0 connecter plusieurs clients au travers d&rsquo;une m\u00eame adresse iPv4. Il est alors impossible depuis internet d&rsquo;acc\u00e9der \u00e0 un des clients qui partagent cette m\u00eame adresse.<\/p>\n\n\n\n<p>Cette modification des conditions d&rsquo;acc\u00e8s \u00e0 \u00e9t\u00e9 r\u00e9alis\u00e9e \u00e0 bas bruit, les FAI ne communicant pas sur les vrais aspects techniques de leur fourniture. C&rsquo;est totalement pass\u00e9 inaper\u00e7u pour la grosse majorit\u00e9 des utilisateurs (en gros, tous ceux qui ne font pas d&rsquo;auto-h\u00e9bergement). La chose est d&rsquo;ailleurs masqu\u00e9e par le fait que la \u00ab\u00a0box internet\u00a0\u00bb livr\u00e9e par le FAI permet la gestion de l&rsquo;IPv6 qui permet l&rsquo;utilisation d&rsquo;un nombre beaucoup, beaucoup plus important d&rsquo;adresses IP (suffisant pour la demande future de points de raccordement).<\/p>\n\n\n\n<p>La consultation des forums techniques m&rsquo;a \u00e9galement permis de comprendre que ces dispositions techniques pouvaient \u00eatre modifi\u00e9es sur demande au FAI (retour \u00e0 l&rsquo;IPv4 d&rsquo;origine). C&rsquo;est la demande de modification qui est un parcours du combattant. Avec RED\/SFR le service assistance peut \u00eatre joint par t\u00e9l\u00e9phone (directement ou par rappel \u00e0 partir de l&rsquo;appli sur smartphone). Le premier contact est fait avec un personnel de niveau 1 (la personne qui lit une fiche et qui en r\u00e9f\u00e8re \u00e0 un sup\u00e9rieur en cas de demande qui ne correspond pas \u00e0 la fiche). Syst\u00e9matiquement la r\u00e9ponse est n\u00e9gative  \u00e0 une demande de rollback IPv4 (retour \u00e0 la version IPv4 d&rsquo;origine). Apr\u00e8s plusieurs tentatives infructueuses je d\u00e9cide de tester l&rsquo;IPv6 qui est propos\u00e9 comme une solution. J&rsquo;ai pass\u00e9 2 jours \u00e0 faire le tour de la question avec multiples exp\u00e9rimentations qui vont de l&rsquo;obtention de nom de domaine param\u00e9tr\u00e9 IPv6 aux param\u00e9trages de la \u00ab\u00a0box internet\u00a0\u00bb pour l&rsquo;utilisation de l&rsquo;IPv6 avec exposition des ports n\u00e9cessaires \u00e0 l&rsquo;acc\u00e8s \u00e0 mes serveurs. Tout fonctionne en r\u00e9seau local. Aucun acc\u00e8s possible depuis l&rsquo;ext\u00e9rieur (internet) \u00e0 mes serveurs. J&rsquo;en d\u00e9duis que l&rsquo;infrastructure du FAI n&rsquo;est pas actuellement en mesure de supporter ce que je demande. D&rsquo;autre part la majeur partie (environ 90%) des services accessibles sur le net fonctionnent avec un adressage IPv4. On peut le v\u00e9rifier \u00e0 l&rsquo;aide de l&rsquo;extension \u00ab\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/addons.mozilla.org\/fr\/android\/addon\/ipvfoo-pmarks\/\" target=\"_blank\">IPvfoo<\/a>\u00a0\u00bb disponible sur Firefox (le navigateur internet) ou sur Chrome.<\/p>\n\n\n\n<p>Retour \u00e0 la case d\u00e9part. Je retente plusieurs fois la demande de rollback aupr\u00e8s de RED\/SFR et cette fois j&rsquo;insiste pour parler \u00e0 un technicien de niveau 2. Au troisi\u00e8me essai ma demande de rollback est accept\u00e9e et 3 heures apr\u00e8s avoir raccroch\u00e9 mon t\u00e9l\u00e9phone, ma \u00ab\u00a0box internet\u00a0\u00bb permet l&rsquo;acc\u00e8s IPv4 avec gestion du NAT. Apr\u00e8s param\u00e9trage des ports du routeur \u00e0 l&rsquo;aide de l&rsquo;interface NAT mes serveurs sont redevenus accessibles de partout dans le monde \u00e0 l&rsquo;aide d&rsquo;une connexion internet.<\/p>\n\n\n\n<p class=\"has-drop-cap\">En conclusion, l&rsquo;auto-h\u00e9bergement de services web \u00e7a demande un peu d&rsquo;expertise, mais aussi et surtout d&rsquo;avoir de la t\u00e9nacit\u00e9 quand il s&rsquo;agit de contacts techniques avec les services clients des FAI.  <\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-table is-style-regular has-small-font-size\"><table class=\"has-background\" style=\"background:linear-gradient(186deg,rgb(238,238,238) 23%,rgb(169,184,195) 100%)\"><tbody><tr><td>IP<\/td><td><em>Internet Protocol<\/em>. Le protocole de communication fondamental de la suite des protocoles internet. Une adresse IP permet d&rsquo;identifier un terminal connect\u00e9 au r\u00e9seau.<\/td><\/tr><tr><td>IPv4<\/td><td>Adressage IP sur un groupe de 4 octets (soit 32 bit). Exemple de notation: 93.23.120.243<\/td><\/tr><tr><td>octet<\/td><td>En <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Informatique\">informatique<\/a>, un <strong>octet<\/strong> est un <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Byte\">multiplet<\/a> de 8&nbsp;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Bit\">bits<\/a> codant une information. Dans ce <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Codage_des_caract%C3%A8res\">syst\u00e8me de codage<\/a>, s&rsquo;appuyant sur le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Syst%C3%A8me_binaire\">syst\u00e8me binaire<\/a>, un octet permet de repr\u00e9senter 2<sup>8<\/sup> nombres, soit 256&nbsp;valeurs diff\u00e9rentes.<\/td><\/tr><\/tbody><\/table><figcaption>glossaire<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Si vous pouvez lire ces quelques lignes c&rsquo;est que mes services auto-h\u00e9berg\u00e9s sont de nouveau en ligne (comprendre: accessibles dans le cyberespace). Il y a 20 jours mon \u00e9pouse et moi d\u00e9m\u00e9nagions dans une maison situ\u00e9e \u00e0 100 m du point de livraison de notre fournisseur d&rsquo;acc\u00e8s internet (la maison est \u00e0 70 m de &hellip; <a href=\"https:\/\/edt.blogdns.net\/wordpress\/2022\/07\/21\/la-fibre-nouvelle-installation-et-experience-de-lipv6\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;La Fibre &#8211; Nouvelle installation et exp\u00e9rience de l&rsquo;IPv6&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[12,13,8],"tags":[31,32,30],"class_list":["post-795","post","type-post","status-publish","format-standard","hentry","category-autohebergement","category-internet","category-vie-privee","tag-auto-hebergement","tag-fibre","tag-internet"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"post-thumbnail":false},"uagb_author_info":{"display_name":"marc","author_link":"https:\/\/edt.blogdns.net\/wordpress\/author\/marc_taviaux\/"},"uagb_comment_info":4,"uagb_excerpt":"Si vous pouvez lire ces quelques lignes c&rsquo;est que mes services auto-h\u00e9berg\u00e9s sont de nouveau en ligne (comprendre: accessibles dans le cyberespace). Il y a 20 jours mon \u00e9pouse et moi d\u00e9m\u00e9nagions dans une maison situ\u00e9e \u00e0 100 m du point de livraison de notre fournisseur d&rsquo;acc\u00e8s internet (la maison est \u00e0 70 m de\u2026","_links":{"self":[{"href":"https:\/\/edt.blogdns.net\/wordpress\/wp-json\/wp\/v2\/posts\/795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edt.blogdns.net\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/edt.blogdns.net\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/edt.blogdns.net\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/edt.blogdns.net\/wordpress\/wp-json\/wp\/v2\/comments?post=795"}],"version-history":[{"count":29,"href":"https:\/\/edt.blogdns.net\/wordpress\/wp-json\/wp\/v2\/posts\/795\/revisions"}],"predecessor-version":[{"id":879,"href":"https:\/\/edt.blogdns.net\/wordpress\/wp-json\/wp\/v2\/posts\/795\/revisions\/879"}],"wp:attachment":[{"href":"https:\/\/edt.blogdns.net\/wordpress\/wp-json\/wp\/v2\/media?parent=795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/edt.blogdns.net\/wordpress\/wp-json\/wp\/v2\/categories?post=795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/edt.blogdns.net\/wordpress\/wp-json\/wp\/v2\/tags?post=795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}